{"id":934,"date":"2017-10-22T17:57:04","date_gmt":"2017-10-22T17:57:04","guid":{"rendered":"https:\/\/p2dm.salzburgresearch.at\/?p=934"},"modified":"2018-05-07T12:55:06","modified_gmt":"2018-05-07T12:55:06","slug":"incluyendo-dulces-en-su-planificacion-de-comidas","status":"publish","type":"post","link":"https:\/\/p2dm.salzburgresearch.at\/es\/incluyendo-dulces-en-su-planificacion-de-comidas\/","title":{"rendered":"Incluyendo dulces en su planificaci\u00f3n de comidas"},"content":{"rendered":"<p>Los dulces cuentan como carbohidratos en su plan de alimentaci\u00f3n (hay que tener en cuenta que no son la mejor opci\u00f3n y procurar evitarlos siempre que se pueda, en caso de tomarlos, deber\u00edan ser de elaboraci\u00f3n casera con harina integral y evitar los dulces de elaboraci\u00f3n industrial). Cuando consuma dulces tiene que planificarlo al inicio de la comida, para intentar equilibrar el consumo de hidratos de carbono en la dieta. Ejemplo ( evitar el consumo de pan en esa comida,arrroz, galletas saladas, cereales, frutas, zumos, leche, yogurt o patatas). Para dejar espacio para los dulces como parte de una comida, tiene las siguientes opciones:<\/p>\n<ul>\n<li>Para que el dulce extra que vamos a tomar no suba en exceso los niveles de glucosa hay que compensar esa comida con alimentos menor cantidad de hidratos de carbono.<\/li>\n<li>Cambie un alimento con alto contenido de carbohidratos (ejemplo no tome arroz, pan, patatas o pasta) en su comida sustituya por algo con menos carbohidratos (ensaladas, verduras con algo de prote\u00ednas tipo pescado, huevos \u00f3 carne, estos no deben ir rebozadoso empanados).<\/li>\n<li>Supongamos que su cena t\u00edpica es una pechuga de pollo a la parrilla, una patata mediana, una rebanada de pan integral, una ensalada de verduras y fruta fresca. Si tiene planificado tomar un bizcocho despu\u00e9s de su comida, busque maneras de mantener controlado el total de carbohidratos en la comida. Evite tomar en esa comida el pan, la fruta y cambiar la patata por otro tipo de verdura con menos cantidadde hidratos de carbono. As\u00ed podemos evitar que el consumo de bizcocho eleve m\u00e1s de lo normal nuestros niveles de glucosa en sangre.<\/li>\n<li>Recordar que el consumo de dulces no debe ser nuestra opci\u00f3n (ya seamos diabeticos \u00f3 no) de postre habitual, ya que nos aportan mucha cantidad de az\u00facares de golpe y es dificil eliminarlos de nuestra sangre. No ser\u00eda la opci\u00f3n m\u00e1s saludable.<\/li>\n<\/ul>\n<p>Para asegurarse de que est\u00e1 consumiendo la cantidad adecuada de hidratos de carbono, lea cuidadosamente las etiquetas de los alimentos. Busque el contenido total de carbohidratos en cada alimento, que le indica la cantidad de carbohidratos que hay en una porci\u00f3n de la comida.<\/p>\n<p>Como parte de la nutrici\u00f3n para la diabetes, los edulcorantes artificiales pueden ofrecer la dulzura del az\u00facar sin las calor\u00edas. Los edulcorantes artificiales pueden ayudarlo a reducir las calor\u00edas y atenerse a un plan de alimentaci\u00f3n saludable, especialmente cuando se utiliza en lugar de az\u00facar en el caf\u00e9 y el t\u00e9, en los cereales o en productos horneados. De hecho, los edulcorantes artificiales se consideran alimentos &#8220;gratuitos&#8221; porque contienen muy pocas calor\u00edas y no cuentan como carbohidratos, grasas o cualquier otro alimento en su plan de comidas.<\/p>\n<p>Los ejemplos de edulcorantes artificiales incluyen: Acesulfamo de potasio , Aspartamo , sacarina , Sucralosa.<\/p>\n<p>Est\u00e9 atento a las calor\u00edas y los carbohidratos. Muchos productos elaborados con edulcorantes artificiales, como productos horneados y yogur o bud\u00edn edulcorado artificialmente, a\u00fan contienen calor\u00edas y carbohidratos que pueden afectar su nivel de az\u00facar en la sangre.<\/p>\n<p>Los alcoholes de az\u00facar, otro tipo de edulcorante con un contenido reducido en calor\u00edas, se utilizan a menudo en caramelos sin az\u00facar, chicles y postres. Revise las etiquetas de los productos para ver palabras como &#8220;isomaltosa&#8221;, &#8220;maltitol&#8221;, &#8220;manitol&#8221;, &#8220;sorbitol&#8221; y &#8220;xilitol&#8221;. Los alimentos sin az\u00facar que contienen alcoholes de az\u00facar todav\u00eda tienen calor\u00edas. Adem\u00e1s, en algunas personas, los alcoholes de az\u00facar pueden causar diarrea.<\/p>\n<p>Dos edulcorantes derivados naturalmente, stevia \u00a0y n\u00e9ctar de agave son otra opci\u00f3n cuando se trata de endulzar la comida. Tenga en cuenta que la relaci\u00f3n az\u00facar-edulcorante es diferente para cada producto, por lo que puede necesitar experimentar hasta encontrar el sabor que desee. Adem\u00e1s, el n\u00e9ctar de agave tiene calor\u00edas y carbohidratos, por lo que debe tenerse en cuenta a la hora de la p\u00e9rdida de peso, la diferencia con otros az\u00facares refinados es que tiene un \u00edndice gluc\u00e9mico m\u00e1s bajo que el az\u00facar, por lo que no afectar\u00e1 tanto su nivel de glucosa, (no se debe abusar de este producto porque su nutriente principal son los hidratos de carbono simples, nada recomendables en general).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los dulces cuentan como carbohidratos en su plan de alimentaci\u00f3n (hay que tener en cuenta que no son la mejor opci\u00f3n y procurar evitarlos siempre que se pueda, en caso de tomarlos, deber\u00edan ser de elaboraci\u00f3n casera con harina integral y evitar los dulces de elaboraci\u00f3n industrial). Cuando consuma dulces tiene que planificarlo al inicio [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[237],"tags":[],"class_list":["post-934","post","type-post","status-publish","format-standard","hentry","category-nutrition-management-es"],"_links":{"self":[{"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/posts\/934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/comments?post=934"}],"version-history":[{"count":5,"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/posts\/934\/revisions"}],"predecessor-version":[{"id":1039,"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/posts\/934\/revisions\/1039"}],"wp:attachment":[{"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/media?parent=934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/categories?post=934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/p2dm.salzburgresearch.at\/es\/wp-json\/wp\/v2\/tags?post=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}